{"id":139323,"date":"2025-02-27T11:02:46","date_gmt":"2025-02-27T11:02:46","guid":{"rendered":"https:\/\/www.socios.com\/fan-token-staking-dictionary\/"},"modified":"2025-03-10T15:54:15","modified_gmt":"2025-03-10T15:54:15","slug":"fan-token-staking-dictionary","status":"publish","type":"post","link":"https:\/\/www.socios.com\/pt-br\/fan-token-staking-dictionary\/","title":{"rendered":"Fan Token Staking Dicion\u00e1rio"},"content":{"rendered":"\n<p>Bem-vindo ao guia completo sobre a terminologia do Fan Token Staking.&nbsp;<\/p>\n\n\n\n<p>Aqui voc\u00ea encontrar\u00e1 todos os termos-chave relacionados ao staking de Fan Token, juntamente com explica\u00e7\u00f5es simples para cada um deles.<\/p>\n\n\n\n<p>Vamos l\u00e1!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Fan Token Staking<\/strong><\/h2>\n\n\n\n<p>Este \u00e9 o termo geral usado para descrever o processo\u00a0 para fazer o staking de seus Fan Tokens na Socios.com para ganhar Reward Points di\u00e1rios. \u00c9 a maneira mais eficaz e simples de ganhar Reward Points, que podem ser usados para reivindicar pr\u00eamios e experi\u00eancias extraordin\u00e1rias.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Stake<\/strong><\/h2>\n\n\n\n<p>Isso significa efetivamente bloquear seus Fan Tokens em troca de Reward Points di\u00e1rios. O staking agora tamb\u00e9m \u00e9 um pr\u00e9-requisito para participar de enquetes na Socios.com e quizzes. Quando voc\u00ea fizer staking de seus Fan Tokens, eles se tornar\u00e3o n\u00e3o negoci\u00e1veis.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Desfazer o Stake<\/strong><\/h2>\n\n\n\n<p>Essa \u00e9 a a\u00e7\u00e3o de desbloquear seus Fan Tokens em stake. Assim que voc\u00ea desbloquear seus Fan Tokens, deixar\u00e1 de ganhar Reward Points di\u00e1rios pelo staking. Depois de desbloquear seus Fan Tokens, voc\u00ea entrar\u00e1 em um per\u00edodo de espera de 7 dias, ao final do qual poder\u00e1 reivindicar seus Fan Tokens de volta.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Per\u00edodo de espera.<\/strong><\/h2>\n\n\n\n<p>Este \u00e9 um per\u00edodo de sete dias que come\u00e7a no momento em que voc\u00ea retira seus Fan Tokens. Seus Fan Tokens permanecem em estado n\u00e3o negoci\u00e1vel durante esse per\u00edodo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Reivindica\u00e7\u00e3o dos Fan Tokens<\/strong><\/h2>\n\n\n\n<p>\u00c9 quando voc\u00ea pode recuperar seus Fan Tokens no final do per\u00edodo de sete dias de espera e us\u00e1-los no mercado.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Reward Points Pool<\/strong><\/h2>\n\n\n\n<p>Essa \u00e9 a quantidade total de Reward Points dispon\u00edveis para serem distribu\u00eddos proporcionalmente entre todos os usu\u00e1rios que fizeram staking com esse Fan Token.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Reward Points dispon\u00edveis<\/strong><\/h2>\n\n\n\n<p>Essa \u00e9 a quantidade total de Reward Points dispon\u00edveis diariamente para cada parceiro, que pode ser influenciada por fatores de mercado.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Ganhos di\u00e1rios estimados<\/strong><\/h2>\n\n\n\n<p>Essa \u00e9 a quantidade de Reward Points, arredondada para o n\u00famero inteiro mais pr\u00f3ximo, que voc\u00ea pode esperar receber do pool em um dia.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Reward Points F\u00f3rmula<\/strong><\/h2>\n\n\n\n<p>Essa \u00e9 a f\u00f3rmula pela qual os ganhos di\u00e1rios s\u00e3o calculados, que \u00e9 a seguinte<\/p>\n\n\n\n<p>[FTs bloqueados por um usu\u00e1rio x Pool de Reward Points]\/ n\u00famero total de FTs bloqueados por todos os usu\u00e1rios<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Total de Fan Tokens em staking<\/strong><\/h2>\n\n\n\n<p>Esse \u00e9 o n\u00famero total de Fan Tokens em staking em um determinado momento.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Taxa de rede<\/strong><\/h2>\n\n\n\n<p>Tamb\u00e9m conhecidas como \u201ctaxas de g\u00e1s\u201d, s\u00e3o encargos n\u00e3o reembols\u00e1veis exigidos para o processamento de transa\u00e7\u00f5es no blockchain. Essas taxas estimadas cobrem os custos de valida\u00e7\u00e3o e podem variar de acordo com o congestionamento da rede e a complexidade da transa\u00e7\u00e3o.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Smart Contract<\/strong><\/h2>\n\n\n\n<p>Trata-se de um programa automatizado em uma blockchain que realiza a\u00e7\u00f5es quando condi\u00e7\u00f5es espec\u00edficas s\u00e3o atendidas, como verificar se um usu\u00e1rio tem Fan Tokens suficientes antes de enviar uma vota\u00e7\u00e3o na blockchain..<\/p>\n\n\n\n<p>Aqui est\u00e1, um guia abrangente para toda a terminologia chave do Fan Token Staking. Se voc\u00ea tamb\u00e9m leu nossos outros artigos educacionais, \u00e9 prov\u00e1vel que j\u00e1 seja um especialista.<br><br>Caso contr\u00e1rio, voc\u00ea pode dar uma olhada neles aqui.<\/p>\n\n\n\n<p><br><a href=\"https:\/\/www.socios.com\/pt-br\/fan-token-staking\/\" target=\"_blank\" rel=\"noreferrer noopener\">Fan Token Staking j\u00e1 est\u00e1 dispon\u00edvel!<br><\/a><a href=\"https:\/\/www.socios.com\/pt-br\/how-to-stake-and-unstake-fan-tokens\/\" target=\"_blank\" rel=\"noreferrer noopener\">Como fazer e desfazer o stake de Fan Tokens<br><\/a><a href=\"https:\/\/www.socios.com\/pt-br\/how-fan-token-staking-impacts-other-features\/\">Como a participa\u00e7\u00e3o no Fan Token\u2122 Staking afeta outros recursos<\/a><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bem-vindo ao guia completo sobre a terminologia do Fan Token Staking.&nbsp; Aqui voc\u00ea encontrar\u00e1 todos os termos-chave relacionados ao staking de Fan Token, juntamente com explica\u00e7\u00f5es simples para cada um deles. Vamos l\u00e1! Fan Token Staking Este \u00e9 o termo geral usado para descrever o processo\u00a0 para fazer o staking de seus Fan Tokens na [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":139178,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[146],"tags":[],"blog-category":[578],"class_list":["post-139323","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-en-pt-br","blog-category-staking-2-pt-br"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fan Token Staking Dicion\u00e1rio - Socios.com<\/title>\n<meta name=\"description\" content=\"Descubra tudo sobre Fan Token Staking na Socios.com. Aprenda como ganhar Reward Points, entender o processo de staking, desfazer o stake e muito mais!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.socios.com\/pt-br\/fan-token-staking-dictionary\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fan Token Staking Dicion\u00e1rio - Socios.com\" \/>\n<meta property=\"og:description\" content=\"Descubra tudo sobre Fan Token Staking na Socios.com. Aprenda como ganhar Reward Points, entender o processo de staking, desfazer o stake e muito mais!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.socios.com\/pt-br\/fan-token-staking-dictionary\/\" \/>\n<meta property=\"og:site_name\" content=\"Socios.com\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-27T11:02:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-10T15:54:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.socios.com\/wp-content\/uploads\/2025\/02\/SO-Fan-Token-Staking-Launch-Awareness-SEO-4-1440x810-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"810\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Socios.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Socios.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.socios.com\\\/pt-br\\\/fan-token-staking-dictionary\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.socios.com\\\/pt-br\\\/fan-token-staking-dictionary\\\/\"},\"author\":{\"name\":\"Socios.com\",\"@id\":\"https:\\\/\\\/www.socios.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/fb1e17f78419b00c336f2f0a0db27142\"},\"headline\":\"Fan Token Staking Dicion\u00e1rio\",\"datePublished\":\"2025-02-27T11:02:46+00:00\",\"dateModified\":\"2025-03-10T15:54:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.socios.com\\\/pt-br\\\/fan-token-staking-dictionary\\\/\"},\"wordCount\":565,\"publisher\":{\"@id\":\"https:\\\/\\\/www.socios.com\\\/pt-br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.socios.com\\\/pt-br\\\/fan-token-staking-dictionary\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.socios.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/SO-Fan-Token-Staking-Launch-Awareness-SEO-4-1440x810-1.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.socios.com\\\/pt-br\\\/fan-token-staking-dictionary\\\/\",\"url\":\"https:\\\/\\\/www.socios.com\\\/pt-br\\\/fan-token-staking-dictionary\\\/\",\"name\":\"Fan Token Staking Dicion\u00e1rio - Socios.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.socios.com\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.socios.com\\\/pt-br\\\/fan-token-staking-dictionary\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.socios.com\\\/pt-br\\\/fan-token-staking-dictionary\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.socios.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/SO-Fan-Token-Staking-Launch-Awareness-SEO-4-1440x810-1.jpg\",\"datePublished\":\"2025-02-27T11:02:46+00:00\",\"dateModified\":\"2025-03-10T15:54:15+00:00\",\"description\":\"Descubra tudo sobre Fan Token Staking na Socios.com. Aprenda como ganhar Reward Points, entender o processo de staking, desfazer o stake e muito mais!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.socios.com\\\/pt-br\\\/fan-token-staking-dictionary\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.socios.com\\\/pt-br\\\/fan-token-staking-dictionary\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.socios.com\\\/pt-br\\\/fan-token-staking-dictionary\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.socios.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/SO-Fan-Token-Staking-Launch-Awareness-SEO-4-1440x810-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.socios.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/SO-Fan-Token-Staking-Launch-Awareness-SEO-4-1440x810-1.jpg\",\"width\":1440,\"height\":810,\"caption\":\"Fan Token Staking Launch - Awareness-SEO-4 1440x810\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.socios.com\\\/pt-br\\\/fan-token-staking-dictionary\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.socios.com\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fan Token Staking Dicion\u00e1rio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.socios.com\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/www.socios.com\\\/pt-br\\\/\",\"name\":\"Socios.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.socios.com\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.socios.com\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.socios.com\\\/pt-br\\\/#organization\",\"name\":\"Socios.com\",\"url\":\"https:\\\/\\\/www.socios.com\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.socios.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.socios.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/socios-logo.webp\",\"contentUrl\":\"https:\\\/\\\/www.socios.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/socios-logo.webp\",\"width\":1920,\"height\":341,\"caption\":\"Socios.com\"},\"image\":{\"@id\":\"https:\\\/\\\/www.socios.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.socios.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/fb1e17f78419b00c336f2f0a0db27142\",\"name\":\"Socios.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5bc7fb5e18757f1e35f806dde506e7dddc340045ab67884dd3f88e56b7eef1a2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5bc7fb5e18757f1e35f806dde506e7dddc340045ab67884dd3f88e56b7eef1a2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5bc7fb5e18757f1e35f806dde506e7dddc340045ab67884dd3f88e56b7eef1a2?s=96&d=mm&r=g\",\"caption\":\"Socios.com\"},\"url\":\"https:\\\/\\\/www.socios.com\\\/pt-br\\\/author\\\/socios\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fan Token Staking Dicion\u00e1rio - Socios.com","description":"Descubra tudo sobre Fan Token Staking na Socios.com. Aprenda como ganhar Reward Points, entender o processo de staking, desfazer o stake e muito mais!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.socios.com\/pt-br\/fan-token-staking-dictionary\/","og_locale":"pt_BR","og_type":"article","og_title":"Fan Token Staking Dicion\u00e1rio - Socios.com","og_description":"Descubra tudo sobre Fan Token Staking na Socios.com. Aprenda como ganhar Reward Points, entender o processo de staking, desfazer o stake e muito mais!","og_url":"https:\/\/www.socios.com\/pt-br\/fan-token-staking-dictionary\/","og_site_name":"Socios.com","article_published_time":"2025-02-27T11:02:46+00:00","article_modified_time":"2025-03-10T15:54:15+00:00","og_image":[{"width":1440,"height":810,"url":"https:\/\/www.socios.com\/wp-content\/uploads\/2025\/02\/SO-Fan-Token-Staking-Launch-Awareness-SEO-4-1440x810-1.jpg","type":"image\/jpeg"}],"author":"Socios.com","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Socios.com","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.socios.com\/pt-br\/fan-token-staking-dictionary\/#article","isPartOf":{"@id":"https:\/\/www.socios.com\/pt-br\/fan-token-staking-dictionary\/"},"author":{"name":"Socios.com","@id":"https:\/\/www.socios.com\/pt-br\/#\/schema\/person\/fb1e17f78419b00c336f2f0a0db27142"},"headline":"Fan Token Staking Dicion\u00e1rio","datePublished":"2025-02-27T11:02:46+00:00","dateModified":"2025-03-10T15:54:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.socios.com\/pt-br\/fan-token-staking-dictionary\/"},"wordCount":565,"publisher":{"@id":"https:\/\/www.socios.com\/pt-br\/#organization"},"image":{"@id":"https:\/\/www.socios.com\/pt-br\/fan-token-staking-dictionary\/#primaryimage"},"thumbnailUrl":"https:\/\/www.socios.com\/wp-content\/uploads\/2025\/02\/SO-Fan-Token-Staking-Launch-Awareness-SEO-4-1440x810-1.jpg","articleSection":["Blog"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.socios.com\/pt-br\/fan-token-staking-dictionary\/","url":"https:\/\/www.socios.com\/pt-br\/fan-token-staking-dictionary\/","name":"Fan Token Staking Dicion\u00e1rio - Socios.com","isPartOf":{"@id":"https:\/\/www.socios.com\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.socios.com\/pt-br\/fan-token-staking-dictionary\/#primaryimage"},"image":{"@id":"https:\/\/www.socios.com\/pt-br\/fan-token-staking-dictionary\/#primaryimage"},"thumbnailUrl":"https:\/\/www.socios.com\/wp-content\/uploads\/2025\/02\/SO-Fan-Token-Staking-Launch-Awareness-SEO-4-1440x810-1.jpg","datePublished":"2025-02-27T11:02:46+00:00","dateModified":"2025-03-10T15:54:15+00:00","description":"Descubra tudo sobre Fan Token Staking na Socios.com. Aprenda como ganhar Reward Points, entender o processo de staking, desfazer o stake e muito mais!","breadcrumb":{"@id":"https:\/\/www.socios.com\/pt-br\/fan-token-staking-dictionary\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.socios.com\/pt-br\/fan-token-staking-dictionary\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.socios.com\/pt-br\/fan-token-staking-dictionary\/#primaryimage","url":"https:\/\/www.socios.com\/wp-content\/uploads\/2025\/02\/SO-Fan-Token-Staking-Launch-Awareness-SEO-4-1440x810-1.jpg","contentUrl":"https:\/\/www.socios.com\/wp-content\/uploads\/2025\/02\/SO-Fan-Token-Staking-Launch-Awareness-SEO-4-1440x810-1.jpg","width":1440,"height":810,"caption":"Fan Token Staking Launch - Awareness-SEO-4 1440x810"},{"@type":"BreadcrumbList","@id":"https:\/\/www.socios.com\/pt-br\/fan-token-staking-dictionary\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.socios.com\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Fan Token Staking Dicion\u00e1rio"}]},{"@type":"WebSite","@id":"https:\/\/www.socios.com\/pt-br\/#website","url":"https:\/\/www.socios.com\/pt-br\/","name":"Socios.com","description":"","publisher":{"@id":"https:\/\/www.socios.com\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.socios.com\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.socios.com\/pt-br\/#organization","name":"Socios.com","url":"https:\/\/www.socios.com\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.socios.com\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/www.socios.com\/wp-content\/uploads\/2023\/09\/socios-logo.webp","contentUrl":"https:\/\/www.socios.com\/wp-content\/uploads\/2023\/09\/socios-logo.webp","width":1920,"height":341,"caption":"Socios.com"},"image":{"@id":"https:\/\/www.socios.com\/pt-br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.socios.com\/pt-br\/#\/schema\/person\/fb1e17f78419b00c336f2f0a0db27142","name":"Socios.com","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/5bc7fb5e18757f1e35f806dde506e7dddc340045ab67884dd3f88e56b7eef1a2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5bc7fb5e18757f1e35f806dde506e7dddc340045ab67884dd3f88e56b7eef1a2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5bc7fb5e18757f1e35f806dde506e7dddc340045ab67884dd3f88e56b7eef1a2?s=96&d=mm&r=g","caption":"Socios.com"},"url":"https:\/\/www.socios.com\/pt-br\/author\/socios\/"}]}},"_links":{"self":[{"href":"https:\/\/www.socios.com\/pt-br\/wp-json\/wp\/v2\/posts\/139323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.socios.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.socios.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.socios.com\/pt-br\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.socios.com\/pt-br\/wp-json\/wp\/v2\/comments?post=139323"}],"version-history":[{"count":0,"href":"https:\/\/www.socios.com\/pt-br\/wp-json\/wp\/v2\/posts\/139323\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.socios.com\/pt-br\/wp-json\/wp\/v2\/media\/139178"}],"wp:attachment":[{"href":"https:\/\/www.socios.com\/pt-br\/wp-json\/wp\/v2\/media?parent=139323"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.socios.com\/pt-br\/wp-json\/wp\/v2\/categories?post=139323"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.socios.com\/pt-br\/wp-json\/wp\/v2\/tags?post=139323"},{"taxonomy":"blog-category","embeddable":true,"href":"https:\/\/www.socios.com\/pt-br\/wp-json\/wp\/v2\/blog-category?post=139323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}